{"id":7768,"date":"2025-12-24T10:34:10","date_gmt":"2025-12-24T09:34:10","guid":{"rendered":"https:\/\/proditysoftware.com\/che-cose-lops-nella-prevenzione-dei-rischi-guida-completa-e-la-sua-evoluzione-con-lintelligenza-artificiale\/"},"modified":"2026-04-22T10:50:21","modified_gmt":"2026-04-22T08:50:21","slug":"che-cose-lops-nella-prevenzione-dei-rischi-guida-completa-e-la-sua-evoluzione-con-lintelligenza-artificiale","status":"publish","type":"post","link":"https:\/\/proditysoftware.com\/it\/che-cose-lops-nella-prevenzione-dei-rischi-guida-completa-e-la-sua-evoluzione-con-lintelligenza-artificiale\/","title":{"rendered":"Che cos&#8217;\u00e8 l&#8217;OPS nella prevenzione dei rischi? Guida completa e la sua evoluzione con l&#8217;Intelligenza Artificiale"},"content":{"rendered":"\n<p>Se cerchi su Google \u00abChe cos&#8217;\u00e8 un OPS nella sicurezza?\u00bb o \u00abChe cos&#8217;\u00e8 un OPS sul lavoro?\u00bb, troverai centinaia di definizioni teoriche. Tuttavia, per un responsabile della sicurezza (<a href=\"https:\/\/proditysoftware.com\/it\/gestione-integrata-ehsq-i-vantaggi-di-centralizzare-ambiente-qualita-e-sicurezza-in-ununica-piattaforma\/\" data-type=\"post\" data-id=\"4612\">EHSQ<\/a>) o un tecnico della prevenzione in uno stabilimento industriale, un OPS \u00e8 molto pi\u00f9 di un acronimo: \u00e8 il vero e proprio termometro della cultura della prevenzione dell&#8217;azienda. <\/p>\n\n\n\n<p>Ma c&#8217;\u00e8 un problema: in molte organizzazioni, le OPS sono diventate una semplice formalit\u00e0 burocratica volta al raggiungimento degli obiettivi, perdendo cos\u00ec il loro vero valore.<\/p>\n\n\n\n<p>In questo articolo non solo risponderemo alle domande fondamentali su cosa sia l&#8217;OPS, ma spiegheremo anche come l&#8217;Intelligenza Artificiale (IA) stia valorizzando questo strumento per prevedere gli incidenti prima che si verifichino.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"785\" height=\"576\" src=\"https:\/\/proditysoftware.com\/wp-content\/uploads\/2025\/10\/Prodity-1.png\" alt=\"OPS nella prevenzione dei rischi\" class=\"wp-image-5387\" srcset=\"https:\/\/proditysoftware.com\/wp-content\/uploads\/2025\/10\/Prodity-1.png 785w, https:\/\/proditysoftware.com\/wp-content\/uploads\/2025\/10\/Prodity-1-300x220.png 300w, https:\/\/proditysoftware.com\/wp-content\/uploads\/2025\/10\/Prodity-1-768x564.png 768w\" sizes=\"(max-width: 785px) 100vw, 785px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">1. Concetti di base: rispondere alle domande pi\u00f9 frequenti<\/h2>\n\n\n\n<p>Basandoci sulle domande pi\u00f9 comuni del settore, chiariamo i concetti chiave per allineare l&#8217;intera organizzazione.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cos&#8217;\u00e8 l&#8217;OPS nella sicurezza e nel lavoro?<\/h3>\n\n\n\n<p><strong>OPS<\/strong> \u00e8 l&#8217;acronimo di <strong>Osservazione Preventiva di Sicurezza<\/strong>. \u00c8 uno strumento fondamentale nell&#8217;ambito della <strong>sicurezza basata sul comportamento (BBS)<\/strong>. <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sul lavoro:<\/strong> l&#8217;atto di osservare una persona mentre svolge un compito specifico per identificare i comportamenti sicuri e quelli a rischio (atti non sicuri).<\/li>\n\n\n\n<li><strong>L&#8217;obiettivo:<\/strong> non si tratta di controllare o biasimare. L&#8217;obiettivo \u00e8 generare un dialogo <em>sul posto<\/em> (feedback) per correggere i comportamenti non sicuri sul momento e rafforzare quelli sicuri. <\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Qual \u00e8 la differenza tra un OPS e un&#8217;ispezione?<\/h3>\n\n\n\n<p>Si tratta di una confusione comune.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ispezione: si<\/strong> concentra sugli <strong>oggetti<\/strong> e sull&#8217;<strong>ambiente<\/strong> (l&#8217;estintore \u00e8 carico? Manca una protezione alla macchina? C&#8217;\u00e8 olio sul pavimento?). Ricerca di <em>condizioni non sicure<\/em>. <\/li>\n\n\n\n<li><strong>OPS: si<\/strong> concentra sulle <strong>persone<\/strong> e sulle loro <strong>azioni<\/strong> (l&#8217;operatore usa le gambe per sollevare il carico? Salta la procedura di blocco?). Cerca i <em>comportamenti<\/em>. <\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Aspetto<\/th><th>Ispezione di sicurezza<\/th><th>Osservatorio di prevenzione (OPS)<\/th><\/tr><\/thead><tbody><tr><td><strong>Tema principale<\/strong><\/td><td>Gli impianti e le attrezzature (\u00abbeni\u00bb)<\/td><td>Le azioni delle persone (\u00abcomportamenti\u00bb)<\/td><\/tr><tr><td><strong>Cosa cerchi<\/strong><\/td><td>Condizioni di insicurezza (oggetti rotti, mancanza di protezioni)<\/td><td>Comportamenti sicuri o insicuri (abitudini lavorative)<\/td><\/tr><tr><td><strong>Obiettivo<\/strong><\/td><td>Ripristinare l&#8217;ambiente fisico<\/td><td>Cambiare la cultura e il comportamento<\/td><\/tr><tr><td><strong>Interazione<\/strong><\/td><td>Di solito si tratta di una lista di controllo tecnica<\/td><td>Richiede dialogo e feedback con il lavoratore<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Perch\u00e9 \u00e8 fondamentale nella prevenzione dei rischi?<\/h3>\n\n\n\n<p>Secondo la <a href=\"https:\/\/es.wikipedia.org\/wiki\/Pir%C3%A1mide_de_Bird\" target=\"_blank\" rel=\"noopener\">piramide di Heinrich<\/a> e studi successivi della SBC, la maggior parte degli incidenti gravi trova la sua causa principale in comportamenti non sicuri non corretti. L&#8217;OPS agisce alla base della piramide: se riduciamo i comportamenti non sicuri attraverso l&#8217;osservazione e il feedback, riduciamo statisticamente la probabilit\u00e0 di un incidente mortale. <\/p>\n\n\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"953\" height=\"584\" src=\"https:\/\/proditysoftware.com\/wp-content\/uploads\/2025\/11\/Calidad-Persona-Tiny.png\" alt=\"\" class=\"wp-image-5588\" srcset=\"https:\/\/proditysoftware.com\/wp-content\/uploads\/2025\/11\/Calidad-Persona-Tiny.png 953w, https:\/\/proditysoftware.com\/wp-content\/uploads\/2025\/11\/Calidad-Persona-Tiny-300x184.png 300w, https:\/\/proditysoftware.com\/wp-content\/uploads\/2025\/11\/Calidad-Persona-Tiny-768x471.png 768w\" sizes=\"(max-width: 953px) 100vw, 953px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">2. Il problema attuale: dati complessi, ore di analisi e pregiudizi umani<\/h2>\n\n\n\n<p>Una volta chiarito cosa sia un OPS, parliamo della realt\u00e0 operativa. Un dipartimento EHSQ in un&#8217;azienda con 300 dipendenti pu\u00f2 ricevere tra le 1000 e le 5000 schede OPS al mese. <\/p>\n\n\n\n<p>Questo crea una tempesta perfetta che ostacola la prevenzione:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">A. Il collo di bottiglia: ore passate a \u201csetacciare i dati\u201d contro la prevenzione effettiva <\/h3>\n\n\n\n<p>Il nemico principale del tecnico della prevenzione \u00e8 il tempo amministrativo.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>La realt\u00e0:<\/strong> un tecnico pu\u00f2 impiegare dai 3 ai 5 minuti per trascrivere una scheda fisica in Excel o per convalidarla in un software. Moltiplicato per 1000 OPS, si tratta di <strong>oltre 40 ore al mese<\/strong> spese solo per &#8220;spostare dati&#8221;. <\/li>\n\n\n\n<li><strong>La conseguenza:<\/strong> i tecnici passano l&#8217;80% del loro tempo a gestire la carta e solo il 20% ad analizzare il problema.  <\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">B. Il filtro umano: i pregiudizi cognitivi<\/h3>\n\n\n\n<p>Anche se avessero a disposizione infinite ore per leggere, il cervello umano non \u00e8 imparziale. Esaminando manualmente centinaia di rapporti, cadiamo in trappole psicologiche involontarie: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Distorsione di conferma<\/strong>: tendiamo a prestare attenzione solo alle operazioni che confermano ci\u00f2 in cui gi\u00e0 crediamo (ad es. \u00ab<em>\u00c8 sempre il turno di notte a dare problemi<\/em>\u00bb), ignorando i dati che contraddicono tale convinzione.<\/li>\n\n\n\n<li>|Affaticamento decisionale: la qualit\u00e0 dell&#8217;analisi del rapporto n. 1 \u00e8 di gran lunga superiore a quella del n. 200. Dopo ore passate a leggere rapporti, il cervello inizia a \u201cscansionare\u201d il testo e a tralasciare dettagli fondamentali per puro esaurimento mentale. <\/li>\n\n\n\n<li>Effetto di recency: attribuiamo un&#8217;importanza eccessiva ai rischi che hanno causato un incidente il giorno prima, diventando cos\u00ec \u201cciechi\u201d di fronte ai segnali silenziosi di pericoli latenti.<\/li>\n<\/ul>\n\n\n\n<p><strong>\u00c8 qui che la gestione tradizionale lascia il posto all&#8217;Intelligenza Artificiale.<\/strong> L&#8217;intelligenza artificiale elimina le ore di trascrizione e analizza l&#8217;OPS numero 500 con lo stesso rigore e la stessa obiettivit\u00e0 della prima, consentendo al tecnico di dedicare il proprio tempo a ci\u00f2 che sa fare meglio: prendere decisioni sul campo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3. Come l&#8217;intelligenza artificiale sta rivoluzionando le osservazioni preventive<\/h2>\n\n\n\n<p>L&#8217;IA non serve a effettuare l&#8217;osservazione (ci\u00f2 richiede empatia umana), ma a elaborare i dati che ne derivano. Grazie all&#8217;elaborazione del Linguaggio Naturale (NLP), l&#8217;IA \u00e8 in grado di leggere e \u201ccomprendere\u201d migliaia di descrizioni delle operazioni in pochi secondi. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized has-custom-border\"><img decoding=\"async\" width=\"494\" height=\"136\" src=\"https:\/\/proditysoftware.com\/wp-content\/uploads\/2026\/02\/firma_ia_IT-comprimida-e1776843983543.png\" alt=\"\" class=\"wp-image-9416\" style=\"border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-left-radius:15px;border-bottom-right-radius:15px;width:651px;height:auto\" srcset=\"https:\/\/proditysoftware.com\/wp-content\/uploads\/2026\/02\/firma_ia_IT-comprimida-e1776843983543.png 494w, https:\/\/proditysoftware.com\/wp-content\/uploads\/2026\/02\/firma_ia_IT-comprimida-e1776843983543-300x83.png 300w\" sizes=\"(max-width: 494px) 100vw, 494px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">A. Rilevamento automatico dei rischi critici<\/h3>\n\n\n\n<p>Se un lavoratore scrive in un sistema di segnalazione degli incidenti (OPS): \u00abIl collega ha improvvisato una piattaforma con dei pallet perch\u00e9 la scala era rotta\u00bb, un sistema tradizionale registrerebbe semplicemente \u00abViolazione della procedura\u00bb. Un&#8217;intelligenza artificiale addestrata in materia di sicurezza rileva le parole chiave e il contesto: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Rischio individuato: lavori in quota in condizioni precarie.<\/li>\n\n\n\n<li>Azione: Avviso immediato al supervisore.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">B. Analisi del sentiment e della cultura<\/h3>\n\n\n\n<p>Che tono usano i lavoratori quando presentano le segnalazioni? L&#8217;IA pu\u00f2 analizzare se le descrizioni denotano: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fretta\/Pressione: \u00abNon l&#8217;ha bloccato perch\u00e9 era urgente portare a termine la produzione\u00bb.<\/li>\n\n\n\n<li>Mancanza di risorse: \u00abNon ha usato i guanti perch\u00e9 non ce n&#8217;erano in magazzino\u00bb.<\/li>\n\n\n\n<li>Stanchezza: \u00abHa saltato quel passaggio perch\u00e9 era stanco alla fine del turno\u00bb.<\/li>\n<\/ul>\n\n\n\n<p>Ci\u00f2 consente al responsabile EHSQ di affrontare la causa principale a livello organizzativo (la pressione produttiva) e non limitarsi ad attribuire la colpa all&#8217;operatore.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">C. Convalida della qualit\u00e0 (La fine dell&#8217;\u00abOPS fantasma\u00bb)<\/h3>\n\n\n\n<p>I tuoi indicatori mostrano molti OPS, ma continuano a verificarsi incidenti? Probabilmente i tuoi OPS sono di scarsa qualit\u00e0. L&#8217;IA \u00e8 in grado di individuare schemi di riempimento:  <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Descrizioni duplicate (&#8220;copy-paste&#8221;).<\/li>\n\n\n\n<li>Operazioni eseguite in tempi impossibili (ad es. 10 osservazioni in 5 minuti).<\/li>\n\n\n\n<li>Incoerenze tra il rischio indicato e la descrizione testuale.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">4. Caso di successo: l&#8217;impatto concreto sul Gruppo Tubacex<\/h2>\n\n\n\n<p>Per comprendere il potenziale di questa tecnologia, non occorre guardare alla Silicon Valley. Nel settore industriale, il Gruppo Tubacex si trovava ad affrontare lo stesso ostacolo di molti dipartimenti EHSQ: un team altamente qualificato che dedicava 15 ore al mese per ogni tecnico esclusivamente a compiti amministrativi di \u201cinserimento dati\u201d e all&#8217;analisi manuale delle osservazioni. <\/p>\n\n\n\n<p>La sfida non era la mancanza di dati, bens\u00ec l&#8217;impossibilit\u00e0 di elaborarli in tempo per poter agire.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Il titolo: 93% di burocrazia in meno<\/h3>\n\n\n\n<p>Dopo aver implementato l&#8217;intelligenza artificiale per la gestione delle operazioni, il cambiamento operativo \u00e8 stato immediato. I dati mostrano una riduzione del 93% dei tempi di analisi, consentendo ai tecnici di passare dall&#8217;ufficio allo stabilimento, dove apportano realmente valore aggiunto. <\/p>\n\n\n\n<p>Tuttavia, il risparmio di tempo \u00e8 solo la punta dell&#8217;iceberg. Ci\u00f2 che \u00e8 stato davvero rivoluzionario \u00e8 stato il modo in cui l&#8217;IA ha permesso di: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Eliminare la soggettivit\u00e0 nella valutazione dei rischi.<\/li>\n\n\n\n<li>Misurare quantitativamente la leadership preventiva, cosa impossibile con il tradizionale Excel.<\/li>\n<\/ul>\n\n\n\n<p><strong>Come ha fatto Tubacex a trasformare un processo reattivo in una fonte di conoscenza predittiva?<\/strong><\/p>\n\n\n\n<p>Abbiamo preparato un <strong>caso di studio dettagliato<\/strong> in cui lo analizziamo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Il confronto completo &#8220;Prima vs. Dopo&#8221;.<\/li>\n\n\n\n<li>In che modo questo ha influito sulla realizzazione della <strong>Sfida 2030.<\/strong><\/li>\n\n\n\n<li>Le impressioni dirette del tuo Coordinatore del Servizio di Prevenzione.<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-base-color has-corp-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/proditysoftware.com\/it\/come-tubacex-ha-rivoluzionato-lorp-con-lai-caso-di-studio\/?utm_source=blog&#038;utm_medium=content&#038;utm_campaign=IA_Prevencion\">Scarica il caso di studio completo<\/a><\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">5. Domande frequenti sull&#8217;IA nella gestione delle OPS<\/h2>\n\n\n\n<p>In questo caso rispondiamo alle preoccupazioni operative dei responsabili della prevenzione modernizzando questo processo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">In che modo l&#8217;intelligenza artificiale pu\u00f2 aiutare ad analizzare le osservazioni di sicurezza precauzionali (PSO)?<\/h3>\n\n\n\n<p>Il sistema utilizza l&#8217;elaborazione del linguaggio naturale (NLP) per leggere migliaia di osservazioni e raggrupparle per temi reali, non solo per categorie predefinite.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;AI \u00e8 valida nei processi OHS verificabili (ISO 45001)?<\/h3>\n\n\n\n<p>S\u00ec. La <a href=\"https:\/\/proditysoftware.com\/it\/iso-45001-cose-e-come-ottenere-una-gestione-efficace-della-sicurezza-e-della-salute\/\">ISO 45001<\/a> d\u00e0 valore al <strong>processo decisionale basato sulle evidenze<\/strong> (clausola 9). L&#8217;utilizzo dell&#8217;IA per analizzare i dati dimostra un profondo impegno per il miglioramento continuo. L&#8217;importante \u00e8 mantenere la tracciabilit\u00e0: che il sistema conservi la registrazione originale (l&#8217;OPS fatta dal lavoratore) e che l&#8217;analisi dell&#8217;IA serva come strumento di supporto alla gestione.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intelligenza artificiale riduce il carico amministrativo dei tecnici della prevenzione?<\/h3>\n\n\n\n<p>In modo drastico. Si stima che i tecnici passino fino al 40% del loro tempo a trascrivere e categorizzare i dati. L&#8217;intelligenza artificiale automatizza la categorizzazione, i grafici e gli avvisi, <strong>liberando fino al 93% di analisi per ogni tecnico<\/strong>.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quali sono i rischi dell&#8217;utilizzo dell&#8217;IA e come vengono controllati?<\/h3>\n\n\n\n<p>Il rischio principale \u00e8 quello di &#8220;falsi positivi&#8221; o &#8220;falsi negativi&#8221; (che l&#8217;IA classifichi erroneamente un&#8217;osservazione critica). <strong>Controllo:<\/strong> il sistema deve funzionare secondo il concetto di &#8221; <em>human-in-the-loop&#8221;<\/em>. L&#8217;IA propone e stabilisce le priorit\u00e0, ma le <strong>azioni critiche<\/strong> (interruzioni del lavoro, sanzioni, modifiche ingegneristiche)<strong> devono sempre essere convalidate da un esperto umano.<\/strong> L&#8217;IA \u00e8 il copilota, non il capitano.  <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Conclusioni per i decisori EHSQ<\/h2>\n\n\n\n<p>Sapere <strong>cos&#8217;\u00e8 un OPS<\/strong> \u00e8 solo il primo passo. La vera sfida oggi non \u00e8 far compilare ai lavoratori dei documenti, ma estrarre informazioni da quelle informazioni per salvare vite umane. <\/p>\n\n\n\n<p>Le osservazioni sulla sicurezza sono la &#8220;voce&#8221; dei tuoi lavoratori. Se oggi queste voci sono intrappolate in un foglio di calcolo che nessuno legge, stai perdendo la tua migliore risorsa preventiva. L&#8217;intelligenza artificiale ti permette di ascoltare queste voci su scala, di identificare le tendenze nascoste e di passare da una prevenzione reattiva a una realmente predittiva.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se cerchi su Google \u00abChe cos&#8217;\u00e8 un OPS nella sicurezza?\u00bb o \u00abChe cos&#8217;\u00e8 un OPS sul lavoro?\u00bb, troverai centinaia di definizioni teoriche. Tuttavia, per un responsabile della sicurezza (EHSQ) o un tecnico della prevenzione in uno stabilimento industriale, un OPS \u00e8 molto pi\u00f9 di un acronimo: \u00e8 il vero e proprio termometro della cultura della [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":7769,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[158,157,141],"tags":[],"class_list":["post-7768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intelligenza-artificiale","category-salute-e-sicurezza-osh","category-senza-categoria"],"_links":{"self":[{"href":"https:\/\/proditysoftware.com\/it\/wp-json\/wp\/v2\/posts\/7768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proditysoftware.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proditysoftware.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proditysoftware.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/proditysoftware.com\/it\/wp-json\/wp\/v2\/comments?post=7768"}],"version-history":[{"count":7,"href":"https:\/\/proditysoftware.com\/it\/wp-json\/wp\/v2\/posts\/7768\/revisions"}],"predecessor-version":[{"id":9445,"href":"https:\/\/proditysoftware.com\/it\/wp-json\/wp\/v2\/posts\/7768\/revisions\/9445"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proditysoftware.com\/it\/wp-json\/wp\/v2\/media\/7769"}],"wp:attachment":[{"href":"https:\/\/proditysoftware.com\/it\/wp-json\/wp\/v2\/media?parent=7768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proditysoftware.com\/it\/wp-json\/wp\/v2\/categories?post=7768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proditysoftware.com\/it\/wp-json\/wp\/v2\/tags?post=7768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}